{"id":33434,"date":"2021-02-20T20:50:28","date_gmt":"2021-02-20T20:50:28","guid":{"rendered":"http:\/\/batelada.com\/?post_type=tnc_col_22831_item&#038;p=33434"},"modified":"2021-02-22T18:06:56","modified_gmt":"2021-02-22T18:06:56","slug":"continente-sul-sur-a-magia-dos-bonecos","status":"publish","type":"tnc_col_22831_item","link":"https:\/\/batelada.com\/index.php\/gsbiblio\/continente-sul-sur-a-magia-dos-bonecos\/","title":{"rendered":"Continente Sul Sur: a magia dos bonecos"},"content":{"rendered":"<p>Uma viagem po\u00e9tica pelo mundo dos bonecos e bonecreiros. Os festivais da cidade de Canela, no Brasil, que se realizaram ao longo de nove anos, s\u00e3o aqui passados em revista. ?Canela entendeu que a arte dos bonecos \u00e9 uma das mais antigas, universais e permanentes formas do fazer art\u00edstico. Compreendeu que ela est\u00e1 presente em todas as civiliza\u00e7?es e \u00e9pocas e \u00e9 decisiva na forma\u00e7\u00e3o da estrutura imagin\u00e1ria da crian\u00e7a e do adulto, pois, de uma maneira ou outra, est\u00e1 ligada ao seu cotidiano como atividade l\u00fadica primordial, embora, como espet\u00e1culo organizado para o p\u00fablico, tenha sido praticada para adultos durante muitos s\u00e9culos. (?) Neste dez anos de Teatro de Bonecos de Canela, o primeiro ano em Caxias, ficou comprovado que, por si s\u00f3, os bonecos s\u00e3o um poderoso meio de comunica\u00e7\u00e3o, de marketing e de investimento com retorno certo. O que \u00e9 preciso entender \u00e9 que poesia vende e sempre vender\u00e1, mas n\u00e3o com a mesma linguagem que se vende papel higi\u00e9nico ou produtos de limpeza em supermercados. A verdade \u00e9 que pelo poder de animar o inanimado, de despertar a \u00e2nima, de soprar com as m\u00e3os e despertar a alma que habita esses fascinantes seres de l\u00e3, pano, madeira ou lata, os bonequeiros s\u00e3o uma esp\u00e9cie de m\u00e1gicos e feiticeiros, verdadeiros cavaleiros andantes produzindo fasc\u00ednio e ilus\u00e3o por onde passam.? (Jo\u00e3o Carlos Tiburski)<\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","class_list":["post-33434","tnc_col_22831_item","type-tnc_col_22831_item","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/batelada.com\/index.php\/wp-json\/wp\/v2\/tnc_col_22831_item\/33434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/batelada.com\/index.php\/wp-json\/wp\/v2\/tnc_col_22831_item"}],"about":[{"href":"https:\/\/batelada.com\/index.php\/wp-json\/wp\/v2\/types\/tnc_col_22831_item"}],"replies":[{"embeddable":true,"href":"https:\/\/batelada.com\/index.php\/wp-json\/wp\/v2\/comments?post=33434"}],"version-history":[{"count":1,"href":"https:\/\/batelada.com\/index.php\/wp-json\/wp\/v2\/tnc_col_22831_item\/33434\/revisions"}],"predecessor-version":[{"id":35113,"href":"https:\/\/batelada.com\/index.php\/wp-json\/wp\/v2\/tnc_col_22831_item\/33434\/revisions\/35113"}],"wp:attachment":[{"href":"https:\/\/batelada.com\/index.php\/wp-json\/wp\/v2\/media?parent=33434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}